{"id":22,"date":"2023-06-27T17:00:04","date_gmt":"2023-06-27T17:00:04","guid":{"rendered":"https:\/\/masqart.nl\/portfolio\/"},"modified":"2024-04-16T19:10:33","modified_gmt":"2024-04-16T19:10:33","slug":"media","status":"publish","type":"page","link":"https:\/\/masqart.nl\/en\/media\/","title":{"rendered":"Media"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"22\" class=\"elementor elementor-22\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a5f833 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a5f833\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4543411\" data-id=\"4543411\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d525c7 gallery-spacing-custom elementor-widget__width-initial elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-image-gallery\" data-id=\"0d525c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1200\" data-carousel-extra='null' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1200px; height: 348px;\" data-original-width=\"1200\" data-original-height=\"348\" > <div class=\"gallery-group images-1\" style=\"width: 198px; height: 348px;\" data-original-width=\"198\" data-original-height=\"348\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"194\"> <meta itemprop=\"height\" content=\"344\"> <img loading=\"lazy\" decoding=\"async\" class=\"\" data-attachment-id=\"1103\" data-orig-file=\"https:\/\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg\" data-orig-size=\"1125,2000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 11 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1698666853&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.25&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"736383F3-DFE8-43F0-BDDE-C2B16F220DE4\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?fit=169%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?fit=576%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?w=194&#038;h=344&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?w=1125&amp;ssl=1 1125w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?resize=169%2C300&amp;ssl=1 169w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?resize=576%2C1024&amp;ssl=1 576w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?resize=768%2C1365&amp;ssl=1 768w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?resize=864%2C1536&amp;ssl=1 864w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?resize=7%2C12&amp;ssl=1 7w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/736383F3-DFE8-43F0-BDDE-C2B16F220DE4-1.jpg?resize=600%2C1067&amp;ssl=1 600w\" width=\"194\" height=\"344\" data-original-width=\"194\" data-original-height=\"344\" itemprop=\"http:\/\/schema.org\/image\" title=\"736383F3-DFE8-43F0-BDDE-C2B16F220DE4\" alt=\"736383F3-DFE8-43F0-BDDE-C2B16F220DE4\" style=\"width: 194px; height: 344px;\" \/> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 197px; height: 348px;\" data-original-width=\"197\" data-original-height=\"348\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"193\"> <meta itemprop=\"height\" content=\"344\"> <img loading=\"lazy\" decoding=\"async\" class=\"\" data-attachment-id=\"1108\" data-orig-file=\"https:\/\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg\" data-orig-size=\"1125,2000\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 11 Pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1702740415&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;4.25&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"F6322EFA-53FC-420C-9DD6-250E292E11C3\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?fit=169%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?fit=576%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?w=193&#038;h=344&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?w=1125&amp;ssl=1 1125w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?resize=169%2C300&amp;ssl=1 169w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?resize=576%2C1024&amp;ssl=1 576w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?resize=768%2C1365&amp;ssl=1 768w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?resize=864%2C1536&amp;ssl=1 864w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?resize=7%2C12&amp;ssl=1 7w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/F6322EFA-53FC-420C-9DD6-250E292E11C3.jpg?resize=600%2C1067&amp;ssl=1 600w\" width=\"193\" height=\"344\" data-original-width=\"193\" data-original-height=\"344\" itemprop=\"http:\/\/schema.org\/image\" title=\"F6322EFA-53FC-420C-9DD6-250E292E11C3\" alt=\"F6322EFA-53FC-420C-9DD6-250E292E11C3\" style=\"width: 193px; height: 344px;\" \/> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 225px; height: 348px;\" data-original-width=\"225\" data-original-height=\"348\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"221\"> <meta itemprop=\"height\" content=\"344\"> <img loading=\"lazy\" decoding=\"async\" class=\"\" data-attachment-id=\"1122\" data-orig-file=\"https:\/\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg\" data-orig-size=\"1125,1748\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1712858080&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_8788\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?fit=193%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?fit=659%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?w=221&#038;h=344&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?w=1125&amp;ssl=1 1125w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?resize=193%2C300&amp;ssl=1 193w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?resize=659%2C1024&amp;ssl=1 659w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?resize=768%2C1193&amp;ssl=1 768w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?resize=989%2C1536&amp;ssl=1 989w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8788.jpg?resize=600%2C932&amp;ssl=1 600w\" width=\"221\" height=\"344\" data-original-width=\"221\" data-original-height=\"344\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_8788\" alt=\"IMG_8788\" style=\"width: 221px; height: 344px;\" \/> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 232px; height: 348px;\" data-original-width=\"232\" data-original-height=\"348\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"228\"> <meta itemprop=\"height\" content=\"344\"> <img loading=\"lazy\" decoding=\"async\" class=\"\" data-attachment-id=\"1099\" data-orig-file=\"https:\/\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg\" data-orig-size=\"1205,1821\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1695462629&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"e2cf2c16-82fb-49c3-93a9-db78f70f6bbc\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?fit=199%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?fit=678%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?w=228&#038;h=344&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?w=1205&amp;ssl=1 1205w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?resize=199%2C300&amp;ssl=1 199w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?resize=678%2C1024&amp;ssl=1 678w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?resize=768%2C1161&amp;ssl=1 768w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?resize=1016%2C1536&amp;ssl=1 1016w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?resize=8%2C12&amp;ssl=1 8w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/e2cf2c16-82fb-49c3-93a9-db78f70f6bbc.jpg?resize=600%2C907&amp;ssl=1 600w\" width=\"228\" height=\"344\" data-original-width=\"228\" data-original-height=\"344\" itemprop=\"http:\/\/schema.org\/image\" title=\"e2cf2c16-82fb-49c3-93a9-db78f70f6bbc\" alt=\"e2cf2c16-82fb-49c3-93a9-db78f70f6bbc\" style=\"width: 228px; height: 344px;\" \/> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 348px; height: 348px;\" data-original-width=\"348\" data-original-height=\"348\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"344\"> <meta itemprop=\"height\" content=\"344\"> <img loading=\"lazy\" decoding=\"async\" class=\"\" data-attachment-id=\"1118\" data-orig-file=\"https:\/\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png\" data-orig-size=\"1080,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_8478\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?fit=1024%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?w=344&#038;h=344&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/IMG_8478.png?resize=100%2C100&amp;ssl=1 100w\" width=\"344\" height=\"344\" data-original-width=\"344\" data-original-height=\"344\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_8478\" alt=\"IMG_8478\" style=\"width: 344px; height: 344px;\" \/> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1200px; height: 767px;\" data-original-width=\"1200\" data-original-height=\"767\" > <div class=\"gallery-group images-1\" style=\"width: 767px; height: 767px;\" data-original-width=\"767\" data-original-height=\"767\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"763\"> <meta itemprop=\"height\" content=\"763\"> <img loading=\"lazy\" decoding=\"async\" class=\"\" data-attachment-id=\"1086\" data-orig-file=\"https:\/\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png\" data-orig-size=\"1080,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Untitled design\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?fit=300%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?fit=1024%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?w=763&#038;h=763&#038;crop=1&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?resize=600%2C600&amp;ssl=1 600w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design.png?resize=100%2C100&amp;ssl=1 100w\" width=\"763\" height=\"763\" data-original-width=\"763\" data-original-height=\"763\" itemprop=\"http:\/\/schema.org\/image\" title=\"Untitled design\" alt=\"Untitled design\" style=\"width: 763px; height: 763px;\" \/> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 433px; height: 767px;\" data-original-width=\"433\" data-original-height=\"767\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <meta itemprop=\"width\" content=\"429\"> <meta itemprop=\"height\" content=\"763\"> <img loading=\"lazy\" decoding=\"async\" class=\"\" data-attachment-id=\"1153\" data-orig-file=\"https:\/\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png\" data-orig-size=\"1080,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Untitled design (4)\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?fit=169%2C300&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?fit=576%2C1024&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?w=429&#038;h=763&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?w=1080&amp;ssl=1 1080w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?resize=169%2C300&amp;ssl=1 169w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?resize=576%2C1024&amp;ssl=1 576w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?resize=768%2C1365&amp;ssl=1 768w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?resize=864%2C1536&amp;ssl=1 864w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?resize=7%2C12&amp;ssl=1 7w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?resize=600%2C1067&amp;ssl=1 600w\" width=\"429\" height=\"763\" data-original-width=\"429\" data-original-height=\"763\" itemprop=\"http:\/\/schema.org\/image\" title=\"Untitled design (4)\" alt=\"Untitled design (4)\" style=\"width: 429px; height: 763px;\" \/> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-179dbfc elementor-hidden-desktop elementor-hidden-tablet elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"179dbfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Afbeelding carrousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 van 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/1.png?fit=576%2C1024&amp;ssl=1\" alt=\"1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 van 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/3.png?fit=576%2C1024&amp;ssl=1\" alt=\"3\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 van 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/4.png?fit=576%2C1024&amp;ssl=1\" alt=\"4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 van 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/5.png?fit=576%2C1024&amp;ssl=1\" alt=\"5\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 van 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/6.png?fit=576%2C1024&amp;ssl=1\" alt=\"6\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 van 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/7.png?fit=576%2C1024&amp;ssl=1\" alt=\"7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 van 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/10.png?fit=576%2C1024&amp;ssl=1\" alt=\"10\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 van 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/17.png?fit=576%2C1024&amp;ssl=1\" alt=\"17\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 van 9\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-4.png?fit=576%2C1024&amp;ssl=1\" alt=\"Untitled design (4)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e52ad30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e52ad30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14e8e3d8\" data-id=\"14e8e3d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36170d7e elementor-widget elementor-widget-heading\" data-id=\"36170d7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Exhibitions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e3f3fa9 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"7e3f3fa9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;speed&quot;:200,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Afbeelding carrousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 van 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/01\/New-Project-8.png?fit=300%2C300&amp;ssl=1\" alt=\"Art Route Leiden 2023\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 van 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/01\/New-Project-7.png?fit=300%2C300&amp;ssl=1\" alt=\"Masters Expo 2023\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 van 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/01\/New-Project-6.png?fit=300%2C300&amp;ssl=1\" alt=\"Gallery: The Aterlier Art Society - Maastricht\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 van 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/01\/New-Project-5.png?fit=300%2C300&amp;ssl=1\" alt=\"Gallery: Santino - Leiden\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 van 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2023\/12\/Untitled-design-copy.webp?fit=300%2C300&amp;ssl=1\" alt=\"Art Caf\u00e9: V.Art - Leiden\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 van 6\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2024\/04\/Untitled-design-3.png?fit=300%2C300&amp;ssl=1\" alt=\"Untitled design (3)\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28897918 elementor-section-full_width elementor-section-content-middle elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"28897918\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-22f4d00a\" data-id=\"22f4d00a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f719600 elementor-widget elementor-widget-image\" data-id=\"1f719600\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2023\/06\/Untitled-design-8-1-1.png?resize=800%2C450&amp;ssl=1\" class=\"attachment-ocean-thumb-ml size-ocean-thumb-ml wp-image-415\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2023\/06\/Untitled-design-8-1-1.png?w=1640&amp;ssl=1 1640w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2023\/06\/Untitled-design-8-1-1.png?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2023\/06\/Untitled-design-8-1-1.png?resize=1024%2C577&amp;ssl=1 1024w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2023\/06\/Untitled-design-8-1-1.png?resize=768%2C433&amp;ssl=1 768w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2023\/06\/Untitled-design-8-1-1.png?resize=1536%2C865&amp;ssl=1 1536w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2023\/06\/Untitled-design-8-1-1.png?resize=800%2C450&amp;ssl=1 800w, https:\/\/i0.wp.com\/masqart.nl\/wp-content\/uploads\/2023\/06\/Untitled-design-8-1-1.png?resize=600%2C338&amp;ssl=1 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2c333c56\" data-id=\"2c333c56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-396768ab elementor-widget elementor-widget-heading\" data-id=\"396768ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get in contact<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20da777c elementor-widget elementor-widget-text-editor\" data-id=\"20da777c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Questions or requests? Feel free to contact me<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38257efa elementor-widget elementor-widget-html\" data-id=\"38257efa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a rel=\"\" role=\"link\" aria-haspopup=\"false\" data-ux=\"Link\" data-aid=\"CONTACT_INFO_EMAIL_REND\" href=\"mailto:Info@masqart.nl\" data-typography=\"LinkAlpha\" data-tccl=\"ux2.CONTACT.contact7.Content.Default.Link.Default.27438.click,click\" style=\"box-sizing: inherit; background-color: rgb(255, 255, 255); color: rgb(0, 0, 0); font-family: Lato, arial, sans-serif; font-size: 20px; overflow-wrap: break-word; cursor: pointer; font-weight: 400; display: inline; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; white-space-collapse: preserve-breaks;\">Info@masqart.nl<\/a><br><a rel=\"\" role=\"link\" aria-haspopup=\"false\" data-ux=\"Link\" data-aid=\"CONTACT_INFO_PHONE_REND\" href=\"tel:+31658834056\" data-typography=\"LinkAlpha\" data-tccl=\"ux2.CONTACT.contact7.Content.Default.Link.Default.27439.click,click\" style=\"box-sizing: inherit; background-color: rgb(255, 255, 255); color: rgb(0, 0, 0); font-family: Lato, arial, sans-serif; font-size: 20px; overflow-wrap: break-word; cursor: pointer; font-weight: 400; display: inline; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; white-space-collapse: preserve-breaks;\">+316 588 340 56<\/a><span style=\"color: rgb(27, 27, 27); font-family: Lato, arial, sans-serif; font-size: 20px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; white-space-collapse: preserve-breaks;\">\r\nLeiden - Netherland<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-489b58db e-grid-align-left e-grid-align-mobile-center elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"489b58db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-whatsapp elementor-repeater-item-1a0557c\" href=\"https:\/\/wa.me\/31658834056\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Whatsapp<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-2d4657c\" href=\"https:\/\/www.instagram.com\/masqart_artist\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c04cff5 elementor-mobile-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"6c04cff5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/masqart.nl\/en\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Exhibitions Kom in contact Vragen of interesse? Neem gerust contact op! Info@masqart.nl+316 588 340 56 Leiden &#8211; Netherland Whatsapp Instagram Contact<\/p>","protected":false},"author":1,"featured_media":1131,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-22","page","type-page","status-publish","has-post-thumbnail","hentry","entry","has-media","owp-thumbs-layout-horizontal","owp-btn-normal","owp-tabs-layout-horizontal","has-no-thumbnails","has-product-nav"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/masqart.nl\/en\/wp-json\/wp\/v2\/pages\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/masqart.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/masqart.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/masqart.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/masqart.nl\/en\/wp-json\/wp\/v2\/comments?post=22"}],"version-history":[{"count":73,"href":"https:\/\/masqart.nl\/en\/wp-json\/wp\/v2\/pages\/22\/revisions"}],"predecessor-version":[{"id":1196,"href":"https:\/\/masqart.nl\/en\/wp-json\/wp\/v2\/pages\/22\/revisions\/1196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/masqart.nl\/en\/wp-json\/wp\/v2\/media\/1131"}],"wp:attachment":[{"href":"https:\/\/masqart.nl\/en\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}